{"id":2394,"date":"2025-04-16T10:02:06","date_gmt":"2025-04-16T10:02:06","guid":{"rendered":"https:\/\/www.juancarlosgarvayo.com\/?post_type=conciertos-y-eventos&#038;p=2394"},"modified":"2025-04-29T19:38:02","modified_gmt":"2025-04-29T19:38:02","slug":"festival-internacional-de-santander","status":"publish","type":"conciertos-y-eventos","link":"https:\/\/www.juancarlosgarvayo.com\/en\/conciertos-y-eventos\/festival-internacional-de-santander\/","title":{"rendered":"Festival Internacional de Santander"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"727\" src=\"https:\/\/www.juancarlosgarvayo.com\/wp-content\/uploads\/2025\/04\/Captura-de-pantalla-2025-04-16-a-las-12.00.07\u202fp.\u202fm-1024x727.png\" alt=\"\" class=\"wp-image-2395\" srcset=\"https:\/\/www.juancarlosgarvayo.com\/wp-content\/uploads\/2025\/04\/Captura-de-pantalla-2025-04-16-a-las-12.00.07\u202fp.\u202fm-1024x727.png 1024w, https:\/\/www.juancarlosgarvayo.com\/wp-content\/uploads\/2025\/04\/Captura-de-pantalla-2025-04-16-a-las-12.00.07\u202fp.\u202fm-300x213.png 300w, https:\/\/www.juancarlosgarvayo.com\/wp-content\/uploads\/2025\/04\/Captura-de-pantalla-2025-04-16-a-las-12.00.07\u202fp.\u202fm-768x545.png 768w, https:\/\/www.juancarlosgarvayo.com\/wp-content\/uploads\/2025\/04\/Captura-de-pantalla-2025-04-16-a-las-12.00.07\u202fp.\u202fm-1536x1090.png 1536w, https:\/\/www.juancarlosgarvayo.com\/wp-content\/uploads\/2025\/04\/Captura-de-pantalla-2025-04-16-a-las-12.00.07\u202fp.\u202fm-2048x1454.png 2048w, https:\/\/www.juancarlosgarvayo.com\/wp-content\/uploads\/2025\/04\/Captura-de-pantalla-2025-04-16-a-las-12.00.07\u202fp.\u202fm-18x12.png 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Moonwinds. M\u00fasica de Benet Casablancas<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Moonwinds. M\u00fasica de Benet Casablancas<\/p>","protected":false},"featured_media":2395,"template":"","class_list":["post-2394","conciertos-y-eventos","type-conciertos-y-eventos","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.juancarlosgarvayo.com\/en\/wp-json\/wp\/v2\/conciertos-y-eventos\/2394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.juancarlosgarvayo.com\/en\/wp-json\/wp\/v2\/conciertos-y-eventos"}],"about":[{"href":"https:\/\/www.juancarlosgarvayo.com\/en\/wp-json\/wp\/v2\/types\/conciertos-y-eventos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.juancarlosgarvayo.com\/en\/wp-json\/wp\/v2\/media\/2395"}],"wp:attachment":[{"href":"https:\/\/www.juancarlosgarvayo.com\/en\/wp-json\/wp\/v2\/media?parent=2394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}